{"id":1024263,"date":"2024-09-27T09:23:31","date_gmt":"2024-09-27T09:23:31","guid":{"rendered":"https:\/\/kudocook.com\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/"},"modified":"2025-03-26T18:34:48","modified_gmt":"2025-03-26T18:34:48","slug":"salade-de-legumes-avec-sauce-utilisant-un-thermomix","status":"publish","type":"recipe","link":"https:\/\/kudocook.com\/fr\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/","title":{"rendered":"Salade de l\u00e9gumes avec sauce utilisant un Thermomix"},"content":{"rendered":"<p>Cette salade de l\u00e9gumes vibrante est comme une parade color\u00e9e dans votre assiette, c\u00e9l\u00e9brant les saveurs fra\u00eeches de la nature ! Originaire du c\u0153ur de la cuisine m\u00e9diterran\u00e9enne, ce plat est non seulement un festin pour les yeux, mais aussi une v\u00e9ritable source de nutriments, rempli de vitamines et de min\u00e9raux. Saviez-vous que les pommes de terre \u00e9taient autrefois consid\u00e9r\u00e9es comme si pr\u00e9cieuses qu&rsquo;elles \u00e9taient utilis\u00e9es comme monnaie dans certaines cultures ? Avec un soup\u00e7on de jus de citron acidul\u00e9 pour \u00e9gayer le tout, cette salade est parfaite pour toute occasion \u2013 que ce soit un pique-nique d&rsquo;\u00e9t\u00e9 ou un d\u00eener douillet en hiver. Alors, retroussez vos manches et pr\u00e9parez-vous \u00e0 m\u00e9langer une medley de l\u00e9gumes qui pourrait faire sourire m\u00eame les mangeurs les plus difficiles !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette salade de l\u00e9gumes vibrante est comme une parade color\u00e9e dans votre assiette, c\u00e9l\u00e9brant les saveurs fra\u00eeches de la nature ! Originaire du c\u0153ur de la cuisine m\u00e9diterran\u00e9enne, ce plat est non seulement un festin pour les yeux, mais aussi&#8230;<\/p>\n","protected":false},"featured_media":1024259,"template":"","meta":{"_acf_changed":false},"categories":[],"tags":[],"recipe_category":[16538,16540,16586,16588],"recipe_meal_course":[16738,16736,16734,16740],"recipe_profile":[16864,16862],"recipe_origin":[16908,16906],"recipe_season":[17282,17278,17284,17274,17276,17280],"compatible_robots":[17366,17368],"class_list":["post-1024263","recipe","type-recipe","status-publish","has-post-thumbnail","hentry","recipe_category-sauces-fr","recipe_category-sauces","recipe_category-salades-fr","recipe_category-salades","recipe_meal_course-accompagnement-fr","recipe_meal_course-plat-principal","recipe_meal_course-plat-principal-fr","recipe_meal_course-accompagnement","recipe_profile-gluten-free","recipe_profile-gluten-free-fr","recipe_origin-mediterraneenne","recipe_origin-mediterraneenne-fr","recipe_season-automne-fr","recipe_season-ete-fr","recipe_season-automne","recipe_season-printemps-fr","recipe_season-printemps","recipe_season-ete","compatible_robots-thermomix-fr","compatible_robots-thermomix"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salade de l\u00e9gumes avec sauce utilisant un Thermomix - KudoCook<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kudocook.com\/fr\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salade de l\u00e9gumes avec sauce utilisant un Thermomix - KudoCook\" \/>\n<meta property=\"og:description\" content=\"Cette salade de l\u00e9gumes vibrante est comme une parade color\u00e9e dans votre assiette, c\u00e9l\u00e9brant les saveurs fra\u00eeches de la nature ! Originaire du c\u0153ur de la cuisine m\u00e9diterran\u00e9enne, ce plat est non seulement un festin pour les yeux, mais aussi...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kudocook.com\/fr\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/\" \/>\n<meta property=\"og:site_name\" content=\"KudoCook\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kudocook\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-26T18:34:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kudocook.com\/wp-content\/uploads\/2024\/09\/627ce8cacef94.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@kudocook\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/recipe\\\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\\\/\",\"url\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/recipe\\\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\\\/\",\"name\":\"Salade de l\u00e9gumes avec sauce utilisant un Thermomix - KudoCook\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/recipe\\\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/recipe\\\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kudocook.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/627ce8cacef94.jpg\",\"datePublished\":\"2024-09-27T09:23:31+00:00\",\"dateModified\":\"2025-03-26T18:34:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/recipe\\\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kudocook.com\\\/fr\\\/recipe\\\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/recipe\\\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kudocook.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/627ce8cacef94.jpg\",\"contentUrl\":\"https:\\\/\\\/kudocook.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/627ce8cacef94.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/recipe\\\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recettes\",\"item\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/recettes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Thermomix\",\"item\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/recettes\\\/?_compatible_robots=thermomix-fr\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Salade de l\u00e9gumes avec sauce utilisant un Thermomix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/\",\"name\":\"KudoCook\",\"description\":\"Conquer a world of culinary possibilities!\",\"publisher\":{\"@id\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/#organization\",\"name\":\"KudoCook\",\"url\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kudocook.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/playstore.png\",\"contentUrl\":\"https:\\\/\\\/kudocook.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/playstore.png\",\"width\":512,\"height\":512,\"caption\":\"KudoCook\"},\"image\":{\"@id\":\"https:\\\/\\\/kudocook.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kudocook\",\"https:\\\/\\\/x.com\\\/kudocook\",\"https:\\\/\\\/www.instagram.com\\\/kudocook\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCIHQma3NSZUyloPZowJSBZQ\",\"https:\\\/\\\/pinterest.com\\\/kudocook\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salade de l\u00e9gumes avec sauce utilisant un Thermomix - KudoCook","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kudocook.com\/fr\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/","og_locale":"fr_FR","og_type":"article","og_title":"Salade de l\u00e9gumes avec sauce utilisant un Thermomix - KudoCook","og_description":"Cette salade de l\u00e9gumes vibrante est comme une parade color\u00e9e dans votre assiette, c\u00e9l\u00e9brant les saveurs fra\u00eeches de la nature ! Originaire du c\u0153ur de la cuisine m\u00e9diterran\u00e9enne, ce plat est non seulement un festin pour les yeux, mais aussi...","og_url":"https:\/\/kudocook.com\/fr\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/","og_site_name":"KudoCook","article_publisher":"https:\/\/www.facebook.com\/kudocook","article_modified_time":"2025-03-26T18:34:48+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/kudocook.com\/wp-content\/uploads\/2024\/09\/627ce8cacef94.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@kudocook","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kudocook.com\/fr\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/","url":"https:\/\/kudocook.com\/fr\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/","name":"Salade de l\u00e9gumes avec sauce utilisant un Thermomix - KudoCook","isPartOf":{"@id":"https:\/\/kudocook.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kudocook.com\/fr\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/#primaryimage"},"image":{"@id":"https:\/\/kudocook.com\/fr\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/#primaryimage"},"thumbnailUrl":"https:\/\/kudocook.com\/wp-content\/uploads\/2024\/09\/627ce8cacef94.jpg","datePublished":"2024-09-27T09:23:31+00:00","dateModified":"2025-03-26T18:34:48+00:00","breadcrumb":{"@id":"https:\/\/kudocook.com\/fr\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kudocook.com\/fr\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kudocook.com\/fr\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/#primaryimage","url":"https:\/\/kudocook.com\/wp-content\/uploads\/2024\/09\/627ce8cacef94.jpg","contentUrl":"https:\/\/kudocook.com\/wp-content\/uploads\/2024\/09\/627ce8cacef94.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/kudocook.com\/fr\/recipe\/salade-de-legumes-avec-sauce-utilisant-un-thermomix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/kudocook.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Recettes","item":"https:\/\/kudocook.com\/fr\/recettes\/"},{"@type":"ListItem","position":3,"name":"Thermomix","item":"https:\/\/kudocook.com\/fr\/recettes\/?_compatible_robots=thermomix-fr"},{"@type":"ListItem","position":4,"name":"Salade de l\u00e9gumes avec sauce utilisant un Thermomix"}]},{"@type":"WebSite","@id":"https:\/\/kudocook.com\/fr\/#website","url":"https:\/\/kudocook.com\/fr\/","name":"KudoCook","description":"Conquer a world of culinary possibilities!","publisher":{"@id":"https:\/\/kudocook.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kudocook.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/kudocook.com\/fr\/#organization","name":"KudoCook","url":"https:\/\/kudocook.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kudocook.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/kudocook.com\/wp-content\/uploads\/2024\/11\/playstore.png","contentUrl":"https:\/\/kudocook.com\/wp-content\/uploads\/2024\/11\/playstore.png","width":512,"height":512,"caption":"KudoCook"},"image":{"@id":"https:\/\/kudocook.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kudocook","https:\/\/x.com\/kudocook","https:\/\/www.instagram.com\/kudocook","https:\/\/www.youtube.com\/channel\/UCIHQma3NSZUyloPZowJSBZQ","https:\/\/pinterest.com\/kudocook"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/recipe\/1024263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/recipe"}],"about":[{"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/types\/recipe"}],"version-history":[{"count":1,"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/recipe\/1024263\/revisions"}],"predecessor-version":[{"id":1024264,"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/recipe\/1024263\/revisions\/1024264"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/media\/1024259"}],"wp:attachment":[{"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/media?parent=1024263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/categories?post=1024263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/tags?post=1024263"},{"taxonomy":"recipe_category","embeddable":true,"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/recipe_category?post=1024263"},{"taxonomy":"recipe_meal_course","embeddable":true,"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/recipe_meal_course?post=1024263"},{"taxonomy":"recipe_profile","embeddable":true,"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/recipe_profile?post=1024263"},{"taxonomy":"recipe_origin","embeddable":true,"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/recipe_origin?post=1024263"},{"taxonomy":"recipe_season","embeddable":true,"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/recipe_season?post=1024263"},{"taxonomy":"compatible_robots","embeddable":true,"href":"https:\/\/kudocook.com\/fr\/wp-json\/wp\/v2\/compatible_robots?post=1024263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}